{"id":49739,"date":"2026-03-09T12:03:41","date_gmt":"2026-03-09T12:03:41","guid":{"rendered":"https:\/\/www.kdmsteel.com\/?p=49739"},"modified":"2026-03-09T12:33:37","modified_gmt":"2026-03-09T12:33:37","slug":"how-does-a-circuit-breaker-work","status":"publish","type":"post","link":"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/","title":{"rendered":"\u00bfC\u00f3mo funciona un disyuntor?"},"content":{"rendered":"<p>Los interruptores autom\u00e1ticos son indispensables para prevenir sobrecargas, cortocircuitos y fallas a tierra, entre otros. Este art\u00edculo explica el principio de funcionamiento del interruptor autom\u00e1tico y le ayudar\u00e1 a comprender por qu\u00e9 son vitales para mantener un funcionamiento confiable y la seguridad el\u00e9ctrica en sus entornos comerciales o industriales.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Palanca<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#Circuit_Breaker\" >Cortacircuitos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#The_Working_Principle_of_Circuit_Breaker\" >Principio de funcionamiento del disyuntor<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#Normal_Operation\" >Funcionamiento normal<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#Fault_Detection\" >Detecci\u00f3n de fallas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#Trip_Mechanism_Activation\" >Activaci\u00f3n del mecanismo de disparo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#Arc_Formation\" >Formaci\u00f3n de arcos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#Arc_Extinction\" >Extinci\u00f3n por arco<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#Circuit_Isolation\" >Aislamiento de circuitos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#Resetting_the_Circuit_Breaker\" >Reiniciar el interruptor autom\u00e1tico<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#FAQ\" >Preguntas frecuentes<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#Can_A_Circuit_Breaker_Fail_to_Trip\" >\u00bfPuede fallar un disyuntor al dispararse?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#What_Is_the_Difference_Between_A_Circuit_Breaker_And_A_Fuse\" >\u00bfCu\u00e1l es la diferencia entre un disyuntor y un fusible?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#How_Do_You_Choose_The_Right_Circuit_Breaker_for_An_Electrical_System\" >\u00bfC\u00f3mo elegir el disyuntor adecuado para un sistema el\u00e9ctrico?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#How_Long_Do_Circuit_Breakers_Typically_Last\" >\u00bfCu\u00e1nto suelen durar los interruptores autom\u00e1ticos?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#What_Are_the_Main_Types_of_Circuit_Breakers_Used_in_Industrial_Systems\" >\u00bfCu\u00e1les son los principales tipos de interruptores autom\u00e1ticos que se utilizan en los sistemas industriales?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#How_Quickly_Does_A_Circuit_Breaker_Respond_to_A_Short_Circuit\" >\u00bfCon qu\u00e9 rapidez responde un disyuntor a un cortocircuito?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/#Final_Thought\" >Reflexi\u00f3n final<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Circuit_Breaker\"><\/span>Cortacircuitos<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49750\" src=\"http:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Circuit-Breaker.jpg\" alt=\"Cortacircuitos\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Circuit-Breaker.jpg 1280w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Circuit-Breaker-150x84.jpg 150w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Circuit-Breaker-768x432.jpg 768w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Circuit-Breaker-18x10.jpg 18w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>La funci\u00f3n principal de un <a href=\"https:\/\/www.kdmsteel.com\/es\/interruptor-automatico-industrial\/\">cortacircuitos<\/a> Su funci\u00f3n es proteger sus sistemas y equipos el\u00e9ctricos de los da\u00f1os causados por altas corrientes, as\u00ed como prevenir incendios, descargas el\u00e9ctricas y otros peligros. A diferencia de los fusibles, los disyuntores se pueden restablecer y reutilizar repetidamente.<\/p>\n<p>En general, en el sistema el\u00e9ctrico, los interruptores autom\u00e1ticos pueden proteger los equipos, reducir los riesgos de incendio, mejorar la seguridad y la fiabilidad del sistema, y permitir una r\u00e1pida recuperaci\u00f3n del circuito.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"The_Working_Principle_of_Circuit_Breaker\"><\/span>Principio de funcionamiento del disyuntor<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49751\" src=\"http:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/The-Working-Principle-of-Circuit-Breaker.jpg\" alt=\"Principio de funcionamiento del disyuntor\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/The-Working-Principle-of-Circuit-Breaker.jpg 1280w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/The-Working-Principle-of-Circuit-Breaker-150x84.jpg 150w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/The-Working-Principle-of-Circuit-Breaker-768x432.jpg 768w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/The-Working-Principle-of-Circuit-Breaker-18x10.jpg 18w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Normal_Operation\"><\/span>Funcionamiento normal<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>En condiciones normales de funcionamiento, el interruptor autom\u00e1tico permanece en la posici\u00f3n de encendido y la corriente fluye a trav\u00e9s del circuito. Los contactos internos del interruptor autom\u00e1tico permanecen cerrados; es decir, el circuito no se interrumpe.<\/p>\n<p>La corriente fluye desde la fuente de alimentaci\u00f3n a trav\u00e9s del circuito y, finalmente, hasta la carga sin ning\u00fan problema. En este estado normal, el disyuntor act\u00faa como un conductor com\u00fan y no ofrece resistencia alguna a la corriente.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Fault_Detection\"><\/span>Detecci\u00f3n de fallas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La funci\u00f3n principal de un interruptor autom\u00e1tico es detectar fallas. Se utiliza para detectar las siguientes condiciones:<\/p>\n<p><strong>Sobrecarga<\/strong>Cuando la corriente excede la capacidad nominal del circuito, esto puede deberse al uso simult\u00e1neo de demasiados dispositivos.<\/p>\n<p><strong>Cortocircuito<\/strong>Se produce una sobrecarga de corriente cuando un cable cargado entra en contacto con un cable neutro o de tierra.<\/p>\n<p><strong>Falla a tierra<\/strong>: Cuando la corriente pasa por una trayectoria inesperada, como cuando un cable cargado entra en contacto con la tierra.<\/p>\n<p>La detecci\u00f3n de fallas se realiza a trav\u00e9s del mecanismo de disparo dentro del interruptor autom\u00e1tico. Dependiendo del dise\u00f1o del interruptor autom\u00e1tico, existen diferentes tipos de unidades de disparo:<\/p>\n<p><strong>Mecanismo de disparo t\u00e9rmico<\/strong>Este tipo de interruptor autom\u00e1tico utiliza tiras bimet\u00e1licas, que se emplean para interrumpir corrientes moderadamente altas de larga duraci\u00f3n. Se doblan cuando la corriente aumenta de temperatura. El mecanismo de liberaci\u00f3n se activa cuando la tira bimet\u00e1lica se dobla hasta un l\u00edmite predeterminado.<\/p>\n<p><strong>Mecanismo de disparo magn\u00e9tico<\/strong>Consiste principalmente en un solenoide (electroim\u00e1n). Cuando hay una sobrecorriente, el exceso de corriente aumenta la fuerza magn\u00e9tica del electroim\u00e1n. Si la corriente supera un cierto umbral, el im\u00e1n tira de la palanca o el \u00e9mbolo, lo que finalmente provoca que salte el disyuntor.<\/p>\n<p><strong>Mecanismo de disparo electr\u00f3nico<\/strong>Utiliza principalmente sensores y microprocesadores para medir con precisi\u00f3n el nivel actual y compararlo con el umbral preestablecido. Este sistema se puede personalizar para satisfacer necesidades de protecci\u00f3n avanzadas e implementar funciones como retardo de tiempo o selectividad.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Trip_Mechanism_Activation\"><\/span>Activaci\u00f3n del mecanismo de disparo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49756\" src=\"http:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Trip-Mechanism-Activation.jpg\" alt=\"Activaci\u00f3n del mecanismo de disparo\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Trip-Mechanism-Activation.jpg 1280w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Trip-Mechanism-Activation-150x84.jpg 150w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Trip-Mechanism-Activation-768x432.jpg 768w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Trip-Mechanism-Activation-18x10.jpg 18w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>El mecanismo de disparo se activa autom\u00e1ticamente cuando el disyuntor detecta una falla, como una sobrecarga, un cortocircuito o una falla a tierra. Al producirse la falla, se activa el mecanismo de operaci\u00f3n y el circuito se desconecta r\u00e1pidamente separando los contactos.<\/p>\n<p>Si su circuito se sobrecarga, un interruptor t\u00e9rmico o electr\u00f3nico retrasar\u00e1 la desconexi\u00f3n y permitir\u00e1 que el circuito se sobrecargue temporalmente. Esto evita las sobretensiones breves causadas por el arranque de equipos o motores de gran potencia y los tiempos de inactividad innecesarios. Una sobrecarga prolongada puede provocar que el disyuntor se dispare.<\/p>\n<p>Si se produce un cortocircuito, la unidad de disparo magn\u00e9tico responder\u00e1 de inmediato. Por lo general, un interruptor autom\u00e1tico electromagn\u00e9tico tambi\u00e9n est\u00e1 equipado con un resorte en su interior. Cuando la fuerza magn\u00e9tica mueve la palanca, la tensi\u00f3n del resorte se libera r\u00e1pidamente. Los contactos independientes accionados por resorte funcionan sin demora, lo que puede ayudar a prevenir da\u00f1os catastr\u00f3ficos.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Arc_Formation\"><\/span>Formaci\u00f3n de arcos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Cuando los contactos del interruptor autom\u00e1tico comienzan a separarse, se forma un arco el\u00e9ctrico entre el contacto m\u00f3vil y el fijo. \u00bfA qu\u00e9 se debe esto? A que la corriente busca un camino para seguir fluyendo. Incluso si los contactos se separan, la corriente a\u00fan puede cruzar el espacio y formar un arco.<\/p>\n<p>Debe tener en cuenta que la temperatura del arco el\u00e9ctrico puede alcanzar miles de grados Celsius. Si no se controla adecuadamente, este arco puede da\u00f1ar el interruptor autom\u00e1tico, provocar un incendio o da\u00f1ar los componentes circundantes.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Arc_Extinction\"><\/span>Extinci\u00f3n por arco<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Si desea un buen control del arco el\u00e9ctrico, puede elegir un interruptor autom\u00e1tico con sistema de extinci\u00f3n de arco. Esto le permite controlar y extinguir el arco de forma segura. El m\u00e9todo de control y extinci\u00f3n utilizado depende principalmente del tipo de interruptor autom\u00e1tico que est\u00e9 utilizando.<\/p>\n<p>Los interruptores de circuito neum\u00e1ticos extinguen el arco principalmente mediante la expulsi\u00f3n de aire cuando se separan los contactos. La presi\u00f3n del aire enfr\u00eda el arco, reduce su temperatura e interrumpe la corriente.<\/p>\n<p>Si utiliza un interruptor de circuito de vac\u00edo en aplicaciones de alto voltaje, el arco se extinguir\u00e1 principalmente en un entorno de vac\u00edo. En un entorno sin gas ni aire, el arco no puede conducir electricidad.<\/p>\n<p>Adem\u00e1s, los interruptores autom\u00e1ticos de hexafluoruro de azufre (interruptores SF\u2086) utilizan gas hexafluoruro de azufre para extinguir el arco el\u00e9ctrico. Esta aplicaci\u00f3n es com\u00fan en sistemas de alta tensi\u00f3n, como las subestaciones el\u00e9ctricas. Estos interruptores autom\u00e1ticos permiten interrumpir la corriente de forma segura sin da\u00f1ar los componentes internos.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Circuit_Isolation\"><\/span>Aislamiento de circuitos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Una vez extinguido el arco el\u00e9ctrico, los contactos del interruptor autom\u00e1tico se abren completamente para aislar eficazmente el circuito. El resto del sistema contin\u00faa funcionando, lo que garantiza que solo se vean afectadas las partes defectuosas del circuito. Esto evita que los cortes de energ\u00eda generalizados provoquen interrupciones en la producci\u00f3n en su entorno industrial o comercial.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Resetting_the_Circuit_Breaker\"><\/span>Reiniciar el interruptor autom\u00e1tico<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Tras solucionar el problema, puede restablecer el interruptor autom\u00e1tico. Antes de restablecerlo, debe reactivar el mecanismo de disparo y devolver los contactos a la posici\u00f3n cerrada. Un interruptor autom\u00e1tico correctamente restablecido puede funcionar con normalidad y proteger el sistema de los efectos de futuras fallas.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"FAQ\"><\/span>Preguntas frecuentes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49752\" src=\"http:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/FAQ-3.jpg\" alt=\"Preguntas frecuentes\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/FAQ-3.jpg 1280w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/FAQ-3-150x84.jpg 150w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/FAQ-3-768x432.jpg 768w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/FAQ-3-18x10.jpg 18w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Can_A_Circuit_Breaker_Fail_to_Trip\"><\/span>\u00bfPuede fallar un disyuntor al dispararse?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>S\u00ed. El fallo en el disparo del disyuntor puede deberse al desgaste mec\u00e1nico, al tama\u00f1o inadecuado del disyuntor, al fallo de la unidad de disparo, etc. Por lo tanto, es necesario inspeccionar y probar el disyuntor peri\u00f3dicamente para garantizar que su funci\u00f3n de protecci\u00f3n est\u00e9 intacta.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"What_Is_the_Difference_Between_A_Circuit_Breaker_And_A_Fuse\"><\/span>\u00bfCu\u00e1l es la diferencia entre un disyuntor y un fusible?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Ambos dispositivos se utilizan para proteger el circuito contra sobrecorrientes, y la diferencia radica en su funcionamiento. Los interruptores autom\u00e1ticos se pueden restablecer tras dispararse, mientras que los fusibles deben reemplazarse. Los interruptores autom\u00e1ticos ofrecen una protecci\u00f3n y capacidad de conmutaci\u00f3n m\u00e1s precisas. Los fusibles tienen un bajo costo inicial, pero altos costos de mantenimiento a largo plazo.<\/p>\n<p>En sistemas comerciales e industriales, los disyuntores fiables y reutilizables son la mejor opci\u00f3n.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"How_Do_You_Choose_The_Right_Circuit_Breaker_for_An_Electrical_System\"><\/span>\u00bfC\u00f3mo elegir el disyuntor adecuado para un sistema el\u00e9ctrico?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Para seleccionar el interruptor autom\u00e1tico adecuado, es necesario evaluar la corriente nominal, la tensi\u00f3n nominal, la capacidad de interrupci\u00f3n, las caracter\u00edsticas de la interfaz, el entorno de instalaci\u00f3n y muchos otros par\u00e1metros. En aplicaciones industriales, tambi\u00e9n es preciso garantizar que el interruptor autom\u00e1tico sea compatible con otros equipos de protecci\u00f3n.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"How_Long_Do_Circuit_Breakers_Typically_Last\"><\/span>\u00bfCu\u00e1nto suelen durar los interruptores autom\u00e1ticos?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Los interruptores autom\u00e1ticos suelen tener una vida \u00fatil de entre 20 y 40 a\u00f1os, aunque esto depende principalmente de factores como el tipo, las condiciones ambientales y el mantenimiento. Por ejemplo, los interruptores autom\u00e1ticos magnetot\u00e9rmicos (MCB) y los interruptores autom\u00e1ticos de caja moldeada (MCCB) pueden utilizarse entre 20 y 30 a\u00f1os con un mantenimiento adecuado. Los interruptores autom\u00e1ticos de alta tensi\u00f3n, como los interruptores de vac\u00edo (VCB) y los interruptores autom\u00e1ticos de SF\u2086, pueden durar entre 30 y 40 a\u00f1os.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"What_Are_the_Main_Types_of_Circuit_Breakers_Used_in_Industrial_Systems\"><\/span>\u00bfCu\u00e1les son los principales tipos de interruptores autom\u00e1ticos que se utilizan en los sistemas industriales?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El MCCB se utiliza principalmente para la protecci\u00f3n de corriente media en equipos industriales, maquinaria y <a href=\"https:\/\/www.kdmsteel.com\/es\/panel-de-distribucion-2\/\">paneles de distribuci\u00f3n<\/a>, que proporciona ajustes regulables de protecci\u00f3n contra sobrecargas y cortocircuitos. El interruptor autom\u00e1tico de corriente (ACB) se utiliza en sistemas de media tensi\u00f3n, para f\u00e1bricas industriales y sistemas de distribuci\u00f3n, con alta capacidad de interrupci\u00f3n.<\/p>\n<p>Adem\u00e1s, existen interruptores de vac\u00edo (VCB) utilizados en subestaciones industriales y redes el\u00e9ctricas, as\u00ed como interruptores autom\u00e1ticos de SF\u2086 para sistemas de transmisi\u00f3n de alta tensi\u00f3n. La elecci\u00f3n se basa en la tensi\u00f3n, la corriente nominal y los requisitos de protecci\u00f3n espec\u00edficos del sistema industrial.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"How_Quickly_Does_A_Circuit_Breaker_Respond_to_A_Short_Circuit\"><\/span>\u00bfCon qu\u00e9 rapidez responde un disyuntor a un cortocircuito?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Su tiempo de respuesta suele estar relacionado con el tipo de interruptor autom\u00e1tico, la gravedad de la falla y el mecanismo de detecci\u00f3n de fallas. Por lo general, los interruptores autom\u00e1ticos con mecanismo de disparo electromagn\u00e9tico (MCCB) tienen un tiempo de reacci\u00f3n a cortocircuitos de entre 1 y 3 milisegundos.<\/p>\n<p>Un interruptor autom\u00e1tico (ACB) para un mecanismo de disparo termomagn\u00e9tico combina protecci\u00f3n t\u00e9rmica (para sobrecargas) y protecci\u00f3n magn\u00e9tica (para cortocircuitos). Reacciona lentamente a las sobrecargas, pero muy r\u00e1pidamente a los cortocircuitos (en 1-5 milisegundos).<\/p>\n<p>Los interruptores autom\u00e1ticos (VCB) equipados con unidades de disparo electr\u00f3nico cuentan con microprocesadores que responden a los cortocircuitos en menos de un milisegundo.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Final_Thought\"><\/span>Reflexi\u00f3n final<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49753\" src=\"http:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Final-Thought.jpg\" alt=\"Reflexi\u00f3n final\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Final-Thought.jpg 1280w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Final-Thought-150x84.jpg 150w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Final-Thought-768x432.jpg 768w, https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/Final-Thought-18x10.jpg 18w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Como fabricante profesional de cajas el\u00e9ctricas, <a href=\"https:\/\/www.kdmsteel.com\/es\/\">KDM<\/a> Podemos proporcionarle diversos tipos de cajas para interruptores autom\u00e1ticos seg\u00fan su aplicaci\u00f3n. Dependiendo de sus necesidades espec\u00edficas, tambi\u00e9n le ofrecemos servicios integrales de producci\u00f3n a medida. Responderemos con prontitud a sus requerimientos y le proporcionaremos muestras. Cont\u00e1ctenos para obtener su soluci\u00f3n personalizada.<\/p>","protected":false},"excerpt":{"rendered":"<p>Circuit breakers are indispensable in preventing overload, short circuit, and ground faults, among others. This article discusses the working principle of the circuit breaker and helps you understand why they are vital for keeping reliable operation and electrical safety in your commercial or industrial environments. Circuit Breaker The main function of a circuit breaker is [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":49755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"disabled","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-49739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How Does a Circuit Breaker Work? - KDM Steel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How Does a Circuit Breaker Work? - KDM Steel\" \/>\n<meta property=\"og:description\" content=\"Circuit breakers are indispensable in preventing overload, short circuit, and ground faults, among others. This article discusses the working principle of the circuit breaker and helps you understand why they are vital for keeping reliable operation and electrical safety in your commercial or industrial environments. Circuit Breaker The main function of a circuit breaker is [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/\" \/>\n<meta property=\"og:site_name\" content=\"KDM Steel\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-09T12:03:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T12:33:37+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/How-Does-a-Circuit-Breaker-Work.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"KDM Steel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"KDM Steel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/how-does-a-circuit-breaker-work\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/how-does-a-circuit-breaker-work\\\/\"},\"author\":{\"name\":\"KDM Steel\",\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/#\\\/schema\\\/person\\\/20f9dd106f5824b75813f83f5a192a5f\"},\"headline\":\"How Does a Circuit Breaker Work?\",\"datePublished\":\"2026-03-09T12:03:41+00:00\",\"dateModified\":\"2026-03-09T12:33:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/how-does-a-circuit-breaker-work\\\/\"},\"wordCount\":1416,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/how-does-a-circuit-breaker-work\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kdmsteel.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/How-Does-a-Circuit-Breaker-Work.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.kdmsteel.com\\\/how-does-a-circuit-breaker-work\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/how-does-a-circuit-breaker-work\\\/\",\"url\":\"https:\\\/\\\/www.kdmsteel.com\\\/how-does-a-circuit-breaker-work\\\/\",\"name\":\"How Does a Circuit Breaker Work? - KDM Steel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/how-does-a-circuit-breaker-work\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/how-does-a-circuit-breaker-work\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kdmsteel.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/How-Does-a-Circuit-Breaker-Work.jpg\",\"datePublished\":\"2026-03-09T12:03:41+00:00\",\"dateModified\":\"2026-03-09T12:33:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/how-does-a-circuit-breaker-work\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kdmsteel.com\\\/how-does-a-circuit-breaker-work\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/how-does-a-circuit-breaker-work\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kdmsteel.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/How-Does-a-Circuit-Breaker-Work.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kdmsteel.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/How-Does-a-Circuit-Breaker-Work.jpg\",\"width\":1280,\"height\":720,\"caption\":\"How Does a Circuit Breaker Work\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/how-does-a-circuit-breaker-work\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kdmsteel.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How Does a Circuit Breaker Work?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/#website\",\"url\":\"https:\\\/\\\/www.kdmsteel.com\\\/\",\"name\":\"KDM Steel\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kdmsteel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/#organization\",\"name\":\"KDM Steel\",\"url\":\"https:\\\/\\\/www.kdmsteel.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kdmsteel.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-kdmsteel-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.kdmsteel.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-kdmsteel-logo.png\",\"width\":998,\"height\":535,\"caption\":\"KDM Steel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kdmsteel.com\\\/#\\\/schema\\\/person\\\/20f9dd106f5824b75813f83f5a192a5f\",\"name\":\"KDM Steel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64b16d13078b1bec337dbb31f593dfd16bc530c88ca9fe9b1c9d2a002408080e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64b16d13078b1bec337dbb31f593dfd16bc530c88ca9fe9b1c9d2a002408080e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64b16d13078b1bec337dbb31f593dfd16bc530c88ca9fe9b1c9d2a002408080e?s=96&d=mm&r=g\",\"caption\":\"KDM Steel\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo funciona un interruptor autom\u00e1tico? - KDM Steel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/","og_locale":"es_ES","og_type":"article","og_title":"How Does a Circuit Breaker Work? - KDM Steel","og_description":"Circuit breakers are indispensable in preventing overload, short circuit, and ground faults, among others. This article discusses the working principle of the circuit breaker and helps you understand why they are vital for keeping reliable operation and electrical safety in your commercial or industrial environments. Circuit Breaker The main function of a circuit breaker is [&hellip;]","og_url":"https:\/\/www.kdmsteel.com\/es\/como-funciona-un-disyuntor\/","og_site_name":"KDM Steel","article_published_time":"2026-03-09T12:03:41+00:00","article_modified_time":"2026-03-09T12:33:37+00:00","og_image":[{"width":1280,"height":720,"url":"http:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/How-Does-a-Circuit-Breaker-Work.jpg","type":"image\/jpeg"}],"author":"KDM Steel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"KDM Steel","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kdmsteel.com\/how-does-a-circuit-breaker-work\/#article","isPartOf":{"@id":"https:\/\/www.kdmsteel.com\/how-does-a-circuit-breaker-work\/"},"author":{"name":"KDM Steel","@id":"https:\/\/www.kdmsteel.com\/#\/schema\/person\/20f9dd106f5824b75813f83f5a192a5f"},"headline":"How Does a Circuit Breaker Work?","datePublished":"2026-03-09T12:03:41+00:00","dateModified":"2026-03-09T12:33:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kdmsteel.com\/how-does-a-circuit-breaker-work\/"},"wordCount":1416,"commentCount":0,"publisher":{"@id":"https:\/\/www.kdmsteel.com\/#organization"},"image":{"@id":"https:\/\/www.kdmsteel.com\/how-does-a-circuit-breaker-work\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/How-Does-a-Circuit-Breaker-Work.jpg","articleSection":["Blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.kdmsteel.com\/how-does-a-circuit-breaker-work\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.kdmsteel.com\/how-does-a-circuit-breaker-work\/","url":"https:\/\/www.kdmsteel.com\/how-does-a-circuit-breaker-work\/","name":"\u00bfC\u00f3mo funciona un interruptor autom\u00e1tico? - KDM Steel","isPartOf":{"@id":"https:\/\/www.kdmsteel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kdmsteel.com\/how-does-a-circuit-breaker-work\/#primaryimage"},"image":{"@id":"https:\/\/www.kdmsteel.com\/how-does-a-circuit-breaker-work\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/How-Does-a-Circuit-Breaker-Work.jpg","datePublished":"2026-03-09T12:03:41+00:00","dateModified":"2026-03-09T12:33:37+00:00","breadcrumb":{"@id":"https:\/\/www.kdmsteel.com\/how-does-a-circuit-breaker-work\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kdmsteel.com\/how-does-a-circuit-breaker-work\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.kdmsteel.com\/how-does-a-circuit-breaker-work\/#primaryimage","url":"https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/How-Does-a-Circuit-Breaker-Work.jpg","contentUrl":"https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2026\/03\/How-Does-a-Circuit-Breaker-Work.jpg","width":1280,"height":720,"caption":"How Does a Circuit Breaker Work"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kdmsteel.com\/how-does-a-circuit-breaker-work\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kdmsteel.com\/"},{"@type":"ListItem","position":2,"name":"How Does a Circuit Breaker Work?"}]},{"@type":"WebSite","@id":"https:\/\/www.kdmsteel.com\/#website","url":"https:\/\/www.kdmsteel.com\/","name":"Acero KDM","description":"","publisher":{"@id":"https:\/\/www.kdmsteel.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kdmsteel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.kdmsteel.com\/#organization","name":"Acero KDM","url":"https:\/\/www.kdmsteel.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.kdmsteel.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2024\/05\/cropped-kdmsteel-logo.png","contentUrl":"https:\/\/www.kdmsteel.com\/wp-content\/uploads\/2024\/05\/cropped-kdmsteel-logo.png","width":998,"height":535,"caption":"KDM Steel"},"image":{"@id":"https:\/\/www.kdmsteel.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kdmsteel.com\/#\/schema\/person\/20f9dd106f5824b75813f83f5a192a5f","name":"Acero KDM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/64b16d13078b1bec337dbb31f593dfd16bc530c88ca9fe9b1c9d2a002408080e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64b16d13078b1bec337dbb31f593dfd16bc530c88ca9fe9b1c9d2a002408080e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64b16d13078b1bec337dbb31f593dfd16bc530c88ca9fe9b1c9d2a002408080e?s=96&d=mm&r=g","caption":"KDM Steel"}}]}},"_links":{"self":[{"href":"https:\/\/www.kdmsteel.com\/es\/wp-json\/wp\/v2\/posts\/49739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kdmsteel.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kdmsteel.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kdmsteel.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kdmsteel.com\/es\/wp-json\/wp\/v2\/comments?post=49739"}],"version-history":[{"count":4,"href":"https:\/\/www.kdmsteel.com\/es\/wp-json\/wp\/v2\/posts\/49739\/revisions"}],"predecessor-version":[{"id":49757,"href":"https:\/\/www.kdmsteel.com\/es\/wp-json\/wp\/v2\/posts\/49739\/revisions\/49757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kdmsteel.com\/es\/wp-json\/wp\/v2\/media\/49755"}],"wp:attachment":[{"href":"https:\/\/www.kdmsteel.com\/es\/wp-json\/wp\/v2\/media?parent=49739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kdmsteel.com\/es\/wp-json\/wp\/v2\/categories?post=49739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kdmsteel.com\/es\/wp-json\/wp\/v2\/tags?post=49739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}